{"id":685,"date":"2018-04-24T15:04:43","date_gmt":"2018-04-24T15:04:43","guid":{"rendered":"http:\/\/redextremaduraverde.org\/web\/?p=685"},"modified":"2018-04-24T15:04:43","modified_gmt":"2018-04-24T15:04:43","slug":"jornada-de-reforestacion-en-guadalupe","status":"publish","type":"post","link":"https:\/\/www.redextremaduraverde.org\/web\/jornada-de-reforestacion-en-guadalupe\/","title":{"rendered":"Jornada de reforestaci\u00f3n en Guadalupe"},"content":{"rendered":"<h2>Entidad: Universidad Popular \u00abGregorio L\u00f3pez \u00bb de Guadalupe<\/h2>\n<p>Direcci\u00f3n postal de la entidad: Calle Vi\u00f1a Mayor n\/s<br \/>\nCorreo electr\u00f3nico de contacto: universidadpopularguadalupe@gmail.com<br \/>\nTel\u00e9fono de contacto: 605278337<\/p>\n<h2>Descripci\u00f3n de la actividad<\/h2>\n<p>Nombre de la experiencia: JORNADA DE SENSIBILIZACI\u00d3N MEDIOAMBIENTAL. REFORESTACI\u00d3N<br \/>\nLugar de realizaci\u00f3n: Antigua escombrera municipal<br \/>\nFecha de realizaci\u00f3n: 20\/03\/2018<\/p>\n<h4>Justificaci\u00f3n<\/h4>\n<p>Se plante\u00f3 esta jornada, para j\u00f3venes del instituto, con el fin de que conocieran el m\u00e9todo de plantar distintas especies arb\u00f3reas, desde el punto de vista de su importancia medioambiental, como generador y protector de vida natural.<\/p>\n<h4>Objetivos:<\/h4>\n<p>Generales:<\/p>\n<ul>\n<li>Promover un Contacto con la naturaleza<\/li>\n<li>Ampliar el conocimiento sobre la naturaleza y el valor ecol\u00f3gico<\/li>\n<li>Sensibilizar sobre la importancia de cuidar el patrimonio natural<\/li>\n<\/ul>\n<p>Espec\u00edficos para los destinatarios de la actividad:<\/p>\n<ul>\n<li>Favorecer la Sensibilizaci\u00f3n ambiental de un grupo que, aunque reciben informaci\u00f3n sobre m\u00e9todos de ecolog\u00eda, les falta continuidad en sus acciones.<\/li>\n<li>Fomentar una vida activa y participativa<\/li>\n<li>Conocer clases de \u00e1rboles (casta\u00f1os, loros, nogales y acebuches)<\/li>\n<li>Conocer m\u00e9todos de recuperaci\u00f3n de espacios naturales<\/li>\n<\/ul>\n<h4>Destinatarios \/ participantes:<\/h4>\n<p>J\u00f3venes de 12 a 13 a\u00f1os.<\/p>\n<p><strong>N\u00famero total de participantes:<\/strong><br \/>\n15 j\u00f3venes de entre 12 y 13 a\u00f1os del IESO Las Villuercas, de Guadalupe<\/p>\n<h4>Descripci\u00f3n de la actividad:<\/h4>\n<p>Previa comunicaci\u00f3n al instituto, se acord\u00f3 en com\u00fan la fecha de realizaci\u00f3n. Posteriormente, los j\u00f3venes participantes, con las profesoras y un agente del medio natural se desplazaron caminando hacia la zona escogida para plantar. (antigua escombrera). Durante el camino el agente del medio rural les dio las explicaciones del entorno<\/p>\n<p>Un veh\u00edculo del ayuntamiento llev\u00f3 los plantones hacia la zona a repoblar. Una vez all\u00ed, los agentes explicaron el m\u00e9todo para plantar bien un \u00e1rbol y ayudaron a los j\u00f3venes. Se seleccionaron los distintos \u00e1rboles seg\u00fan las zonas a repoblar y se hacieron grupos de trabajo<\/p>\n<h4>Evaluaci\u00f3n de la actividad:<\/h4>\n<p>Los participantes, tanto j\u00f3venes, profesores, agentes y personal del Ayuntamiento y U.P. disfrutaron de la experiencia, aprendiendo los pasos para plantar correctamente y de los mejores espacios seg\u00fan las clases de \u00e1rboles.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entidad: Universidad Popular \u00abGregorio L\u00f3pez \u00bb de Guadalupe Direcci\u00f3n postal de la entidad: Calle Vi\u00f1a Mayor n\/s Correo electr\u00f3nico de contacto: universidadpopularguadalupe@gmail.com Tel\u00e9fono de contacto: 605278337 Descripci\u00f3n de la actividad Nombre de la experiencia: JORNADA DE SENSIBILIZACI\u00d3N MEDIOAMBIENTAL. REFORESTACI\u00d3N Lugar de realizaci\u00f3n: Antigua escombrera municipal Fecha de realizaci\u00f3n: 20\/03\/2018 Justificaci\u00f3n Se plante\u00f3 esta jornada, para j\u00f3venes del instituto, con el fin de que conocieran el m\u00e9todo de plantar distintas especies arb\u00f3reas, desde el punto de vista de su importancia medioambiental,&hellip;<\/p>\n","protected":false},"author":3,"featured_media":686,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[5],"tags":[10],"class_list":["post-685","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-iniciativas-verdes","tag-guadalupe","post-has-thumbnail"],"jetpack_featured_media_url":"https:\/\/www.redextremaduraverde.org\/web\/wp-content\/uploads\/2018\/04\/foto-reforestacion.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9MpCs-b3","_links":{"self":[{"href":"https:\/\/www.redextremaduraverde.org\/web\/wp-json\/wp\/v2\/posts\/685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redextremaduraverde.org\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redextremaduraverde.org\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redextremaduraverde.org\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redextremaduraverde.org\/web\/wp-json\/wp\/v2\/comments?post=685"}],"version-history":[{"count":1,"href":"https:\/\/www.redextremaduraverde.org\/web\/wp-json\/wp\/v2\/posts\/685\/revisions"}],"predecessor-version":[{"id":687,"href":"https:\/\/www.redextremaduraverde.org\/web\/wp-json\/wp\/v2\/posts\/685\/revisions\/687"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redextremaduraverde.org\/web\/wp-json\/wp\/v2\/media\/686"}],"wp:attachment":[{"href":"https:\/\/www.redextremaduraverde.org\/web\/wp-json\/wp\/v2\/media?parent=685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redextremaduraverde.org\/web\/wp-json\/wp\/v2\/categories?post=685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redextremaduraverde.org\/web\/wp-json\/wp\/v2\/tags?post=685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}