{"id":659,"date":"2018-03-05T08:03:31","date_gmt":"2018-03-05T08:03:31","guid":{"rendered":"http:\/\/redextremaduraverde.org\/web\/?p=659"},"modified":"2018-03-05T08:03:31","modified_gmt":"2018-03-05T08:03:31","slug":"elaboracion-de-jabones-naturales-en-olivenza","status":"publish","type":"post","link":"https:\/\/www.redextremaduraverde.org\/web\/elaboracion-de-jabones-naturales-en-olivenza\/","title":{"rendered":"Elaboraci\u00f3n de jabones naturales en Olivenza"},"content":{"rendered":"<h2>Entidad: UNIVERSIDAD POPULAR DE OLIVENZA<\/h2>\n<p>Responsable t\u00e9cnico de la experiencia: GEMA CONDI\u00d1O<br \/>\nDirecci\u00f3n postal de la entidad: Calle Hern\u00e1n Cort\u00e9s, s\/n<br \/>\nCorreo electr\u00f3nico de contacto: upolivenza@hotmail.com<br \/>\nTel\u00e9fono de contacto: 924 492068 \/ 697165181<\/p>\n<h2>Descripci\u00f3n de la actividad<\/h2>\n<p>Nombre de la experiencia: Actividad de sensibilizaci\u00f3n y concienciaci\u00f3n en econom\u00eda circular, Taller de dinamizaci\u00f3n ciudadana \u00abelaboraci\u00f3n de jabones naturales\u00bb<br \/>\nLugar de realizaci\u00f3n: UNIVERSIDAD POPULAR DE OLIVENZA<br \/>\nFecha de realizaci\u00f3n: 11 DE DICIEMBRE DE 2017<\/p>\n<h4>Justificaci\u00f3n<\/h4>\n<p>Se desarrolla esta actividad que se basa en la reutilizaci\u00f3n del aceite que normalmente se deshecha con el fin de darle usos alternativos del mismo.<\/p>\n<h4>Objetivos:<\/h4>\n<p>Proporcionar los conocimientos b\u00e1sico para la elaboraci\u00f3n de jabones artesanales con aceites usados con la t\u00e9cnica del proceso en fr\u00edo y as\u00ed poner de manifiesto la importancia de la econom\u00eda circular.<\/p>\n<h4>Destinatarios \/ participantes:<\/h4>\n<p>Poblaci\u00f3n en general<\/p>\n<p><strong>N\u00famero total de participantes:<\/strong><br \/>\n13<\/p>\n<h4>Descripci\u00f3n de la actividad:<\/h4>\n<p>Sesi\u00f3n presencial de elaboraci\u00f3n de jabones artesanales mediante aceites reciclados y con t\u00e9cnicas tradicionales, precedida de una charla previa sobre la estrategia Extremadura 2030.<\/p>\n<h4>Evaluaci\u00f3n de la actividad:<\/h4>\n<p>Los participantes de la actividad quedaron muy satisfechos<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entidad: UNIVERSIDAD POPULAR DE OLIVENZA Responsable t\u00e9cnico de la experiencia: GEMA CONDI\u00d1O Direcci\u00f3n postal de la entidad: Calle Hern\u00e1n Cort\u00e9s, s\/n Correo electr\u00f3nico de contacto: upolivenza@hotmail.com Tel\u00e9fono de contacto: 924 492068 \/ 697165181 Descripci\u00f3n de la actividad Nombre de la experiencia: Actividad de sensibilizaci\u00f3n y concienciaci\u00f3n en econom\u00eda circular, Taller de dinamizaci\u00f3n ciudadana \u00abelaboraci\u00f3n de jabones naturales\u00bb Lugar de realizaci\u00f3n: UNIVERSIDAD POPULAR DE OLIVENZA Fecha de realizaci\u00f3n: 11 DE DICIEMBRE DE 2017 Justificaci\u00f3n Se desarrolla esta actividad que se basa&hellip;<\/p>\n","protected":false},"author":3,"featured_media":660,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[5],"tags":[12],"class_list":["post-659","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-iniciativas-verdes","tag-olivenza","post-has-thumbnail"],"jetpack_featured_media_url":"https:\/\/www.redextremaduraverde.org\/web\/wp-content\/uploads\/2018\/03\/6oGastronomica31.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9MpCs-aD","_links":{"self":[{"href":"https:\/\/www.redextremaduraverde.org\/web\/wp-json\/wp\/v2\/posts\/659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redextremaduraverde.org\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redextremaduraverde.org\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redextremaduraverde.org\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redextremaduraverde.org\/web\/wp-json\/wp\/v2\/comments?post=659"}],"version-history":[{"count":1,"href":"https:\/\/www.redextremaduraverde.org\/web\/wp-json\/wp\/v2\/posts\/659\/revisions"}],"predecessor-version":[{"id":661,"href":"https:\/\/www.redextremaduraverde.org\/web\/wp-json\/wp\/v2\/posts\/659\/revisions\/661"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redextremaduraverde.org\/web\/wp-json\/wp\/v2\/media\/660"}],"wp:attachment":[{"href":"https:\/\/www.redextremaduraverde.org\/web\/wp-json\/wp\/v2\/media?parent=659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redextremaduraverde.org\/web\/wp-json\/wp\/v2\/categories?post=659"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redextremaduraverde.org\/web\/wp-json\/wp\/v2\/tags?post=659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}