{"id":409,"date":"2017-07-06T07:36:39","date_gmt":"2017-07-06T07:36:39","guid":{"rendered":"http:\/\/redextremaduraverde.org\/web\/?p=409"},"modified":"2017-07-06T07:38:04","modified_gmt":"2017-07-06T07:38:04","slug":"concierto-didactico-con-material-reciclado-en-navalvillar-de-pela","status":"publish","type":"post","link":"https:\/\/www.redextremaduraverde.org\/web\/concierto-didactico-con-material-reciclado-en-navalvillar-de-pela\/","title":{"rendered":"Concierto did\u00e1ctico con material reciclado en Navalvillar de Pela"},"content":{"rendered":"<h2>Entidad: Up Navalvillar de Pela<\/h2>\n<p>Direcci\u00f3n postal de la entidad: C\/ Lepanto. N\u00ba:1 06760 Navalvillar de Pela. Badajoz<br \/>\nCorreo electr\u00f3nico de contacto: universipopular@navalvillardepela.es<br \/>\nTel\u00e9fono de contacto: 924861800. Extensi\u00f3n 250<\/p>\n<h2>Descripci\u00f3n de la actividad<\/h2>\n<p>Nombre de la experiencia: Concierto did\u00e1ctico con material reciclado<br \/>\nLugar de realizaci\u00f3n: Navalvillar de Pela<br \/>\nFecha de realizaci\u00f3n: 5 junio 2017<\/p>\n<h4>Justificaci\u00f3n<\/h4>\n<p>En el marco del D\u00eda Mundial del Medio Ambiente se celebra este concierto did\u00e1ctico ofrecido por los alumnos de la Escuela Municipal de M\u00fasica de Navalvillar de Pela para los alumnos de infantil y primaria del C.E.I.P. Nra. Sra. de Guadalupe<\/p>\n<h4>Objetivos:<\/h4>\n<ul>\n<li>Aplicar y utilizar diferentes estrategias pedag\u00f3gicas utilizando materiales reciclados.<\/li>\n<li>Motivar a los ni\u00f1os para que se conviertan en agentes activos, utilizando un desarrollo sostenible y equilibrado dentro de un proyecto ambiental<\/li>\n<\/ul>\n<h4>Destinatarios \/ participantes:<\/h4>\n<p>Alumnos de la Escuela Municipal de M\u00fasica de Navalvillar de Pela y alumnos de infantil y primaria del C.E.I.P. Nra. Sra. de Guadalupe.<\/p>\n<h4>Descripci\u00f3n de la actividad:<\/h4>\n<p>Celebraci\u00f3n de un concierto did\u00e1ctico en la casa de cultura de Navalvillar de Pela a a cargo de los alumnos de la escuela municipal de m\u00fasica utilizando material reciclado para percusi\u00f3n.<\/p>\n<h4>Evaluaci\u00f3n de la actividad:<\/h4>\n<p>Por parte del colegio muy buena aceptaci\u00f3n de la actividad<\/p>\n<p>N\u00ba de participantes: 225 ni\u00f1os de educaci\u00f3n infantil y primaria<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entidad: Up Navalvillar de Pela Direcci\u00f3n postal de la entidad: C\/ Lepanto. N\u00ba:1 06760 Navalvillar de Pela. Badajoz Correo electr\u00f3nico de contacto: universipopular@navalvillardepela.es Tel\u00e9fono de contacto: 924861800. Extensi\u00f3n 250 Descripci\u00f3n de la actividad Nombre de la experiencia: Concierto did\u00e1ctico con material reciclado Lugar de realizaci\u00f3n: Navalvillar de Pela Fecha de realizaci\u00f3n: 5 junio 2017 Justificaci\u00f3n En el marco del D\u00eda Mundial del Medio Ambiente se celebra este concierto did\u00e1ctico ofrecido por los alumnos de la Escuela Municipal de M\u00fasica de&hellip;<\/p>\n","protected":false},"author":3,"featured_media":410,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[5],"tags":[14],"class_list":["post-409","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-iniciativas-verdes","tag-navalvillar-de-pela","post-has-thumbnail"],"jetpack_featured_media_url":"https:\/\/www.redextremaduraverde.org\/web\/wp-content\/uploads\/2017\/07\/maracas.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9MpCs-6B","_links":{"self":[{"href":"https:\/\/www.redextremaduraverde.org\/web\/wp-json\/wp\/v2\/posts\/409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redextremaduraverde.org\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redextremaduraverde.org\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redextremaduraverde.org\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redextremaduraverde.org\/web\/wp-json\/wp\/v2\/comments?post=409"}],"version-history":[{"count":1,"href":"https:\/\/www.redextremaduraverde.org\/web\/wp-json\/wp\/v2\/posts\/409\/revisions"}],"predecessor-version":[{"id":411,"href":"https:\/\/www.redextremaduraverde.org\/web\/wp-json\/wp\/v2\/posts\/409\/revisions\/411"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redextremaduraverde.org\/web\/wp-json\/wp\/v2\/media\/410"}],"wp:attachment":[{"href":"https:\/\/www.redextremaduraverde.org\/web\/wp-json\/wp\/v2\/media?parent=409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redextremaduraverde.org\/web\/wp-json\/wp\/v2\/categories?post=409"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redextremaduraverde.org\/web\/wp-json\/wp\/v2\/tags?post=409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}